{"id":3281,"date":"2014-11-25T18:36:57","date_gmt":"2014-11-25T17:36:57","guid":{"rendered":"https:\/\/content.www.institutomaxilofacial.com\/blog\/?p=3281"},"modified":"2020-06-25T15:03:51","modified_gmt":"2020-06-25T13:03:51","slug":"que-relacion-existe-entre-la-diabetes-y-la-salud-bucal","status":"publish","type":"post","link":"https:\/\/content.www.institutomaxilofacial.com\/es\/2014\/11\/25\/que-relacion-existe-entre-la-diabetes-y-la-salud-bucal\/","title":{"rendered":"\u00bfQu\u00e9 relaci\u00f3n existe entre la Diabetes y la Salud Bucal?"},"content":{"rendered":"\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-right kksr-valign-top\"\n    data-payload='{&quot;align&quot;:&quot;right&quot;,&quot;id&quot;:&quot;3281&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;top&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 votos)&quot;,&quot;size&quot;:&quot;30&quot;,&quot;title&quot;:&quot;\u00bfQu\u00e9 relaci\u00f3n existe entre la Diabetes y la Salud Bucal?&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 30px; height: 30px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 30px; height: 30px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 30px; height: 30px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 30px; height: 30px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 30px; height: 30px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 30px; height: 30px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 30px; height: 30px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 30px; height: 30px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 30px; height: 30px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 30px; height: 30px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 24px;\">\n            <span class=\"kksr-muted\">Rate this post<\/span>\n    <\/div>\n    <\/div>\n<p style=\"text-align: justify;\">La investigaci\u00f3n cl\u00ednica revela, de forma consistente en los \u00faltimos a\u00f1os, una vinculaci\u00f3n estrecha entre la <strong>diabetes<\/strong> <em><strong>mellitus<\/strong> <\/em>y la <strong>enfermedad periodontal<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Coincidiendo con la celebraci\u00f3n del <strong>D\u00eda Mundial de la Diabetes<\/strong>, la <a href=\"http:\/\/bit.ly\/1uBZyn9\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Sociedad Espa\u00f1ola de Periodoncia<\/strong><\/a> (<strong>SEPA<\/strong>) de la cual la <strong>Dra. Vanessa Ruiz Magaz<\/strong> es miembro especialista, sugiere una mayor implicaci\u00f3n del <strong>diab\u00e9tico<\/strong> en el control de su enfermedad y en el cuidado <strong>bucodental<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Las personas que padecen <strong>diabetes<\/strong> no s\u00f3lo son m\u00e1s susceptibles a padecer una <strong>enfermedad gingival<\/strong> severa sino que adem\u00e1s, la misma <strong>enfermedad gingival<\/strong> severa puede acabar afectando el control de la glucosa en la sangre y contribuir al empeoramiento de la diabetes.<\/p>\n<p style=\"text-align: justify;\">Se recomienda mantener una excelente <strong>higiene oral<\/strong>, controlar su dieta y visitar a su especialista en <strong>enc\u00edas<\/strong> cada 6 meses.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La investigaci\u00f3n cl\u00ednica revela, de forma consistente en los \u00faltimos a\u00f1os, una vinculaci\u00f3n estrecha entre la diabetes mellitus y la enfermedad periodontal.<br \/>\nCoincidiendo con la celebraci\u00f3n del D\u00eda Mundial de la Diabetes, la Sociedad Espa\u00f1ola de Periodoncia (SEPA) de la cual la Dra. Vanessa Ruiz Magaz &#8230;<\/p>\n","protected":false},"author":7,"featured_media":3283,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[94],"tags":[350,383,65,95],"class_list":["post-3281","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-periodoncia","tag-diabetes","tag-hospital-quiron-teknon","tag-instituto-de-cirugia-maxilofacial-e-implantologia","tag-periodoncia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfQu\u00e9 relaci\u00f3n existe entre la Diabetes y la Salud Bucal? - Instituto Maxilofacial<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/content.www.institutomaxilofacial.com\/es\/wp-json\/wp\/v2\/posts\/3281\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 relaci\u00f3n existe entre la Diabetes y la Salud Bucal? - Instituto Maxilofacial\" \/>\n<meta property=\"og:description\" content=\"La investigaci\u00f3n cl\u00ednica revela, de forma consistente en los \u00faltimos a\u00f1os, una vinculaci\u00f3n estrecha entre la diabetes mellitus y la enfermedad periodontal. Coincidiendo con la celebraci\u00f3n del D\u00eda Mundial de la Diabetes, la Sociedad Espa\u00f1ola de Periodoncia (SEPA) de la cual la Dra. Vanessa Ruiz Magaz ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/content.www.institutomaxilofacial.com\/en\/2014\/11\/25\/que-relacion-existe-entre-la-diabetes-y-la-salud-bucal\/\" \/>\n<meta property=\"og:site_name\" content=\"Instituto Maxilofacial\" \/>\n<meta property=\"article:published_time\" content=\"2014-11-25T17:36:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-25T13:03:51+00:00\" \/>\n<meta name=\"author\" content=\"Dra. Vanessa Ruiz Magaz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dra. Vanessa Ruiz Magaz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/content.www.institutomaxilofacial.com\\\/en\\\/2014\\\/11\\\/25\\\/que-relacion-existe-entre-la-diabetes-y-la-salud-bucal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/content.www.institutomaxilofacial.com\\\/en\\\/2014\\\/11\\\/25\\\/que-relacion-existe-entre-la-diabetes-y-la-salud-bucal\\\/\"},\"author\":{\"name\":\"Dra. Vanessa Ruiz Magaz\",\"@id\":\"https:\\\/\\\/content.www.institutomaxilofacial.com\\\/ca\\\/#\\\/schema\\\/person\\\/8d601dafb17a5b565a34050c4da6263c\"},\"headline\":\"\u00bfQu\u00e9 relaci\u00f3n existe entre la Diabetes y la Salud Bucal?\",\"datePublished\":\"2014-11-25T17:36:57+00:00\",\"dateModified\":\"2020-06-25T13:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/content.www.institutomaxilofacial.com\\\/en\\\/2014\\\/11\\\/25\\\/que-relacion-existe-entre-la-diabetes-y-la-salud-bucal\\\/\"},\"wordCount\":151,\"image\":{\"@id\":\"https:\\\/\\\/content.www.institutomaxilofacial.com\\\/en\\\/2014\\\/11\\\/25\\\/que-relacion-existe-entre-la-diabetes-y-la-salud-bucal\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"diabetes\",\"Hospital Quir\u00f3n Teknon\",\"Instituto de Cirug\u00eda maxilofacial e implantolog\u00eda\",\"Periodoncia\"],\"articleSection\":[\"Periodoncia\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/content.www.institutomaxilofacial.com\\\/en\\\/2014\\\/11\\\/25\\\/que-relacion-existe-entre-la-diabetes-y-la-salud-bucal\\\/\",\"url\":\"https:\\\/\\\/content.www.institutomaxilofacial.com\\\/en\\\/2014\\\/11\\\/25\\\/que-relacion-existe-entre-la-diabetes-y-la-salud-bucal\\\/\",\"name\":\"\u00bfQu\u00e9 relaci\u00f3n existe entre la Diabetes y la Salud Bucal? - Instituto Maxilofacial\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/content.www.institutomaxilofacial.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/content.www.institutomaxilofacial.com\\\/en\\\/2014\\\/11\\\/25\\\/que-relacion-existe-entre-la-diabetes-y-la-salud-bucal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/content.www.institutomaxilofacial.com\\\/en\\\/2014\\\/11\\\/25\\\/que-relacion-existe-entre-la-diabetes-y-la-salud-bucal\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2014-11-25T17:36:57+00:00\",\"dateModified\":\"2020-06-25T13:03:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/content.www.institutomaxilofacial.com\\\/ca\\\/#\\\/schema\\\/person\\\/8d601dafb17a5b565a34050c4da6263c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/content.www.institutomaxilofacial.com\\\/en\\\/2014\\\/11\\\/25\\\/que-relacion-existe-entre-la-diabetes-y-la-salud-bucal\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/content.www.institutomaxilofacial.com\\\/en\\\/2014\\\/11\\\/25\\\/que-relacion-existe-entre-la-diabetes-y-la-salud-bucal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/content.www.institutomaxilofacial.com\\\/en\\\/2014\\\/11\\\/25\\\/que-relacion-existe-entre-la-diabetes-y-la-salud-bucal\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/content.www.institutomaxilofacial.com\\\/en\\\/2014\\\/11\\\/25\\\/que-relacion-existe-entre-la-diabetes-y-la-salud-bucal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/content.www.institutomaxilofacial.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 relaci\u00f3n existe entre la Diabetes y la Salud Bucal?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/content.www.institutomaxilofacial.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/content.www.institutomaxilofacial.com\\\/ca\\\/\",\"name\":\"Instituto Maxilofacial\",\"description\":\"Expertos en Cirug\u00eda Ortogn\u00e1tica y Ortofacial.  Precisi\u00f3n, experiencia y pasi\u00f3n por la innovaci\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/content.www.institutomaxilofacial.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/content.www.institutomaxilofacial.com\\\/ca\\\/#\\\/schema\\\/person\\\/8d601dafb17a5b565a34050c4da6263c\",\"name\":\"Dra. Vanessa Ruiz Magaz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d497b2e91d4511ec05d2d52d2318e02e75bbf9d52989d53745ef1d949baab1c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d497b2e91d4511ec05d2d52d2318e02e75bbf9d52989d53745ef1d949baab1c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d497b2e91d4511ec05d2d52d2318e02e75bbf9d52989d53745ef1d949baab1c?s=96&d=mm&r=g\",\"caption\":\"Dra. Vanessa Ruiz Magaz\"},\"description\":\"Licenciada en Odontolog\u00eda. Postgrado en Periodoncia. Postgrado en Implantolog\u00eda Oral. Profesora del M\u00e1ster en Periodoncia de la Universidad Internacional de Catalunya (UIC).\",\"url\":\"https:\\\/\\\/content.www.institutomaxilofacial.com\\\/es\\\/author\\\/vruiz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 relaci\u00f3n existe entre la Diabetes y la Salud Bucal? - Instituto Maxilofacial","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/content.www.institutomaxilofacial.com\/es\/wp-json\/wp\/v2\/posts\/3281\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 relaci\u00f3n existe entre la Diabetes y la Salud Bucal? - Instituto Maxilofacial","og_description":"La investigaci\u00f3n cl\u00ednica revela, de forma consistente en los \u00faltimos a\u00f1os, una vinculaci\u00f3n estrecha entre la diabetes mellitus y la enfermedad periodontal. Coincidiendo con la celebraci\u00f3n del D\u00eda Mundial de la Diabetes, la Sociedad Espa\u00f1ola de Periodoncia (SEPA) de la cual la Dra. Vanessa Ruiz Magaz ...","og_url":"https:\/\/content.www.institutomaxilofacial.com\/en\/2014\/11\/25\/que-relacion-existe-entre-la-diabetes-y-la-salud-bucal\/","og_site_name":"Instituto Maxilofacial","article_published_time":"2014-11-25T17:36:57+00:00","article_modified_time":"2020-06-25T13:03:51+00:00","author":"Dra. Vanessa Ruiz Magaz","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Dra. Vanessa Ruiz Magaz","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/content.www.institutomaxilofacial.com\/en\/2014\/11\/25\/que-relacion-existe-entre-la-diabetes-y-la-salud-bucal\/#article","isPartOf":{"@id":"https:\/\/content.www.institutomaxilofacial.com\/en\/2014\/11\/25\/que-relacion-existe-entre-la-diabetes-y-la-salud-bucal\/"},"author":{"name":"Dra. Vanessa Ruiz Magaz","@id":"https:\/\/content.www.institutomaxilofacial.com\/ca\/#\/schema\/person\/8d601dafb17a5b565a34050c4da6263c"},"headline":"\u00bfQu\u00e9 relaci\u00f3n existe entre la Diabetes y la Salud Bucal?","datePublished":"2014-11-25T17:36:57+00:00","dateModified":"2020-06-25T13:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/content.www.institutomaxilofacial.com\/en\/2014\/11\/25\/que-relacion-existe-entre-la-diabetes-y-la-salud-bucal\/"},"wordCount":151,"image":{"@id":"https:\/\/content.www.institutomaxilofacial.com\/en\/2014\/11\/25\/que-relacion-existe-entre-la-diabetes-y-la-salud-bucal\/#primaryimage"},"thumbnailUrl":"","keywords":["diabetes","Hospital Quir\u00f3n Teknon","Instituto de Cirug\u00eda maxilofacial e implantolog\u00eda","Periodoncia"],"articleSection":["Periodoncia"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/content.www.institutomaxilofacial.com\/en\/2014\/11\/25\/que-relacion-existe-entre-la-diabetes-y-la-salud-bucal\/","url":"https:\/\/content.www.institutomaxilofacial.com\/en\/2014\/11\/25\/que-relacion-existe-entre-la-diabetes-y-la-salud-bucal\/","name":"\u00bfQu\u00e9 relaci\u00f3n existe entre la Diabetes y la Salud Bucal? - Instituto Maxilofacial","isPartOf":{"@id":"https:\/\/content.www.institutomaxilofacial.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/content.www.institutomaxilofacial.com\/en\/2014\/11\/25\/que-relacion-existe-entre-la-diabetes-y-la-salud-bucal\/#primaryimage"},"image":{"@id":"https:\/\/content.www.institutomaxilofacial.com\/en\/2014\/11\/25\/que-relacion-existe-entre-la-diabetes-y-la-salud-bucal\/#primaryimage"},"thumbnailUrl":"","datePublished":"2014-11-25T17:36:57+00:00","dateModified":"2020-06-25T13:03:51+00:00","author":{"@id":"https:\/\/content.www.institutomaxilofacial.com\/ca\/#\/schema\/person\/8d601dafb17a5b565a34050c4da6263c"},"breadcrumb":{"@id":"https:\/\/content.www.institutomaxilofacial.com\/en\/2014\/11\/25\/que-relacion-existe-entre-la-diabetes-y-la-salud-bucal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/content.www.institutomaxilofacial.com\/en\/2014\/11\/25\/que-relacion-existe-entre-la-diabetes-y-la-salud-bucal\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/content.www.institutomaxilofacial.com\/en\/2014\/11\/25\/que-relacion-existe-entre-la-diabetes-y-la-salud-bucal\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/content.www.institutomaxilofacial.com\/en\/2014\/11\/25\/que-relacion-existe-entre-la-diabetes-y-la-salud-bucal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/content.www.institutomaxilofacial.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 relaci\u00f3n existe entre la Diabetes y la Salud Bucal?"}]},{"@type":"WebSite","@id":"https:\/\/content.www.institutomaxilofacial.com\/ca\/#website","url":"https:\/\/content.www.institutomaxilofacial.com\/ca\/","name":"Instituto Maxilofacial","description":"Expertos en Cirug\u00eda Ortogn\u00e1tica y Ortofacial.  Precisi\u00f3n, experiencia y pasi\u00f3n por la innovaci\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/content.www.institutomaxilofacial.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/content.www.institutomaxilofacial.com\/ca\/#\/schema\/person\/8d601dafb17a5b565a34050c4da6263c","name":"Dra. Vanessa Ruiz Magaz","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6d497b2e91d4511ec05d2d52d2318e02e75bbf9d52989d53745ef1d949baab1c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6d497b2e91d4511ec05d2d52d2318e02e75bbf9d52989d53745ef1d949baab1c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6d497b2e91d4511ec05d2d52d2318e02e75bbf9d52989d53745ef1d949baab1c?s=96&d=mm&r=g","caption":"Dra. Vanessa Ruiz Magaz"},"description":"Licenciada en Odontolog\u00eda. Postgrado en Periodoncia. Postgrado en Implantolog\u00eda Oral. Profesora del M\u00e1ster en Periodoncia de la Universidad Internacional de Catalunya (UIC).","url":"https:\/\/content.www.institutomaxilofacial.com\/es\/author\/vruiz\/"}]}},"meta_box":{"post-excerpt":""},"_links":{"self":[{"href":"https:\/\/content.www.institutomaxilofacial.com\/es\/wp-json\/wp\/v2\/posts\/3281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/content.www.institutomaxilofacial.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/content.www.institutomaxilofacial.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/content.www.institutomaxilofacial.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/content.www.institutomaxilofacial.com\/es\/wp-json\/wp\/v2\/comments?post=3281"}],"version-history":[{"count":2,"href":"https:\/\/content.www.institutomaxilofacial.com\/es\/wp-json\/wp\/v2\/posts\/3281\/revisions"}],"predecessor-version":[{"id":11382,"href":"https:\/\/content.www.institutomaxilofacial.com\/es\/wp-json\/wp\/v2\/posts\/3281\/revisions\/11382"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/content.www.institutomaxilofacial.com\/es\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/content.www.institutomaxilofacial.com\/es\/wp-json\/wp\/v2\/media?parent=3281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/content.www.institutomaxilofacial.com\/es\/wp-json\/wp\/v2\/categories?post=3281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/content.www.institutomaxilofacial.com\/es\/wp-json\/wp\/v2\/tags?post=3281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}